{"id":2447,"date":"2022-12-14T14:43:43","date_gmt":"2022-12-14T14:43:43","guid":{"rendered":"http:\/\/dev.astoria.hr\/?page_id=2447"},"modified":"2023-01-18T12:51:09","modified_gmt":"2023-01-18T12:51:09","slug":"vorwort-von-kunsthistorikerin","status":"publish","type":"page","link":"https:\/\/hans-h-binder.com\/de\/vorwort-von-kunsthistorikerin\/","title":{"rendered":"Vorwort von Kunsthistorikerin"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-image:linear-gradient(174deg, var(--awb-color2) 52%,var(--awb-color1) 52%);background-position: left top;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:var(--awb-color3);border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:83.2%;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\">@media only screen and (max-width:1024px) {.fusion-title.fusion-title-1{margin-top:27px!important; margin-right:0px!important;margin-bottom:20px!important;margin-left:0px!important;}}@media only screen and (max-width:640px) {.fusion-title.fusion-title-1{margin-top:10px!important; margin-right:0px!important;margin-bottom:20px!important; margin-left:0px!important;}}<\/style><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-two\" style=\"margin-top:27px;margin-right:0px;margin-bottom:20px;margin-left:0px;\"><h2 class=\"title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:72;line-height:1.28;\"><strong>Vorwort von Kunsthistorikerin HR Dr. Veronika Birke f\u00fcr den Katalog 2008<\/strong><\/h2><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-0{width:100% !important;margin-top : 20px;margin-bottom : 20px;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-0{width:100% !important;order : 0;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-0{width:100% !important;order : 0;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_3_5 3_5 fusion-flex-column fusion-animated\" data-animationType=\"fadeInDown\" data-animationDuration=\"0.8\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-center fusion-content-layout-column\" style=\"background-position:left top;background-blend-mode: overlay;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-separator\" style=\"align-self: flex-start;margin-right:auto;margin-top:8px;margin-bottom:20px;width:100%;max-width:32px;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"border-color:var(--awb-color8);border-top-width:2px;\"><\/div><\/div><div class=\"fusion-text fusion-text-1\" style=\"text-transform:none;\"><p>Hans Binder<\/p>\n<p>Aquarelle und Radierungen<\/p>\n<p>Hans Binder hat &#8211; auf der Suche nach einem roten Faden durch seine k\u00fcnstlerische Arbeit \u2013 ein \u201ekunsthistorisches\u201c Motto gefunden: \u201eChaos und Ordnung\u201c, das eine lange Geschichte hat. Er nennt sein k\u00fcnstlerisches Anliegen eine Symbiose von \u201eEmotion und Analytik\u201c, eine andere Beschreibung f\u00fcr eine fortw\u00e4hrende Auseinandersetzung zwischen Gegens\u00e4tzen, die in der Theorie der Kunstgeschichte immer wieder eingehender Betrachtung unterzogen wurden. Es ist das unaufl\u00f6sbare Spiel zwischen \u201edisegno\u201c und \u201ecolore\u201c, zwischen der Linie und der Farbe. Ist die Linie der Leitfaden der Idee, die Eindeutigkeit, die Pr\u00e4zision, so ist die Farbe das Chaos, das Ausufernde, das Lebendige, Organische und Bereichernde. Farbe allein w\u00fcrde verschwimmen, ausrinnen, sich nicht zurechtfinden, w\u00e4re da nicht die Linie, die Halt gibt und den Gedanken zur n\u00e4chsten Wegkreuzung f\u00fchrt.<\/p>\n<p>\u00dcberlegungen im weiten Feld von Malerei, Zeichnung und Druckgraphik lassen diese Unterscheidungen immer wieder wahrnehmbar werden. Es sind die fein gezogenen Grenzen, an denen die Linien halten oder sich verlieren und wo sich Malerei in Chaos aufl\u00f6st oder seine Struktur beh\u00e4lt.<\/p>\n<p>Schon als Heranwachsender richtete Hans Binder sein Interesse auf die Natur. Zun\u00e4chst aber besch\u00e4ftigte er sich mit dem Kopieren von Landschaftsbildern aus der Wachau. Nach radierten Ansichten ber\u00fchmter Geh\u00f6fte und bekannten Ansichten aus dem Donautal schulte er sein Auge und seine noch unge\u00fcbte Hand. Das Abzeichnen dieser Vorlagen diente ihm allerdings nur als Einstieg in den Klettergarten k\u00fcnstlerischer Suche. Sehr bald begann er direkt nach der Natur zu zeichnen und zu aquarellieren. Lockere Federzeichnungen in Tusche und Bister entstanden \u2013 zumal ihm auch die Akademie der bildenden K\u00fcnste den Weg in eine zeichnerische Freiheit wies. Aquarelle ben\u00f6tigen viel Wasser, so viel, dass ganze Pf\u00fctzen und kleine Seen zwischen den Farbr\u00e4ndern auf dem sich wellenden nassen Papier entstehen, wodurch sich reizvolle, \u201eimpressionistisch\u201c anmutende Akzente bilden k\u00f6nnen. Die Suche nach den Formen der Natur bezieht sich nicht so sehr auf die Konturen oder Strukturen des Vorbildes, sondern mehr auf die Impressionen und die Stimmungen, die durch Farbe vermittelt werden. So entstehen schon fr\u00fch einerseits skizzenhafte Federzeichnungen und andererseits stimmungsvolle Aquarelle.<\/p>\n<p>Die k\u00fcnstlerische Besch\u00e4ftigung musste w\u00e4hrend der Jahre seines Berufslebens in den Hintergrund treten, blieb aber immer eine lebendige Quelle der Erfahrung.<\/p>\n<p>Hinzu kamen in den vergangenen Jahren mehrere Reisen, die Hans Binder deutlich beeinflusst haben. Eine Griechenlandreise in den 70er-Jahren hinterlie\u00df Spuren, die fortan seine Handschrift pr\u00e4gen sollten. Aus kunsthistorischer Sicht war diese Reise eine Grand Tour, da sie zu den antiken Vorbildern f\u00fchrte. S\u00e4ulen, Spolien und die mediterrane Leuchtkraft der Farben beeinflussten seine Themen und seine Palette.<\/p>\n<p>Sp\u00e4ter folgte eine Reise nach \u00c4gypten, die wahrscheinlich noch pr\u00e4gender f\u00fcr Hans Binder wurde, da sich die Wiedergabe der \u00e4gyptischen Pyramiden, des Sandes und des glei\u00dfenden Lichts der farblichen Wiedergabe unserer Breiten widersetzt. Der Himmel ist nicht nur blau und die W\u00fcste ist nicht blo\u00df gelb, sondern bietet eine F\u00fclle farblicher Nuancen, deren k\u00fcnstlerische Umsetzung durchaus eine Herausforderung ist. Schatten gehen ins Dunkelviolett und der Sand wird geradezu als Malmittel empfunden.<\/p>\n<p>Auch in Sizilien findet der K\u00fcnstler diese Intensit\u00e4t der Natur und gibt sich ihr hin. Doch er will noch mehr. Die Linien, die Konturen und die Fl\u00e4chen und Tiefen sind nicht genug, er sucht das Profil auf der Oberfl\u00e4che seiner Zeichnungen, so als ob ihm die Landschaft durch die Bildfl\u00e4che entgegenw\u00fcchse. Hans Binder gestattet sich einen Kunstgriff. Er klebt Papierst\u00fccke, solche mit Profil wie z.B. Teile aus Schachtelkarton oder zerknitterte Seidenpapiere, die nass wie zusammen geschobene Hautst\u00fccke wirken, in die Oberfl\u00e4che seiner Landschaftsdarstellungen. F\u00fcr den K\u00fcnstler sind sie Landschaft in der Landschaft und werden von ihm als \u201eZuf\u00e4lligkeiten\u201c wahrgenommen und dienen doch gleichzeitig als willkommene Aufforderungen zur Gestaltung. In den Kan\u00e4len des gefalteten Papiers l\u00e4uft Farbe zusammen, kleine Flussl\u00e4ufe bilden sich und T\u00e4ler verzweigen sich zu neuen Landschaften. Deckwei\u00df gibt der Oberfl\u00e4che Profil und bildet gleichzeitig Br\u00fccken zu farbigen Tiefebenen, in denen sich Gr\u00fcn, Gr\u00fcngelb und Ocker sammelt. Binder spielt mit den sogenannten Zuf\u00e4lligkeiten und schiebt den Horizont nach oben, so dass &#8211; wie im mittelalterlichen Tafelbild &#8211; Landschaft als steil ansteigendes Terrain erscheint, an dessen oberer Kante H\u00e4user und D\u00e4cher von einem dahinter liegenden Land k\u00fcnden. Insofern hat Hans Binder seine Handschrift zu einer manieristischen Ausdruckform gesteigert, die ihm auch seine Grenzen weist.<\/p>\n<p>Beeinflusst durch Reisen in den mediterranen Raum entwickelte Hans Binder eine Palette zwischen Braun, Gr\u00fcn und Gelb, die durch einen Aufenthalt in Zakopane (Polen) eine weitere farbliche Bereicherung erfuhr. Dunkler Wald, steile D\u00e4cher, wie man sie noch in Polen findet, und ein dunkles Gr\u00fcn, das sich mit Blauviolett zu einer geradezu mystisch m\u00e4rchenhaften Stimmung verbindet, bringt neue Akzente in die gro\u00dfformatigen Aquarelle.<\/p>\n<p>Konsequent verfolgt Hans Binder das Thema Landschaft, das f\u00fcr ihn eine immerw\u00e4hrende Herausforderung darstellt, dem Wesentlichen der Natur nahe zu kommen. Er sucht nicht allein die Wiedergabe der Landschaft, ihren Duktus und ihre Farbigkeit zu fassen sondern ebenso das in ihr enthaltene charakteristische Wesen herauszuarbeiten. Das Mystische von Zakopane ebenso wie das Licht und die Kleinteiligkeit der \u00c4cker und Waldst\u00fccke des Burgenlandes bei Neumarkt an der Raab sprechen in der Erinnerung des Betrachters das Wesentliche, das einer Landschaft innewohnt, an.<\/p>\n<p>In letzter Zeit wurde Neumarkt an der Raab f\u00fcr Hans Binder ein wichtiger Ort k\u00fcnstlerischer Erfahrung und Weiterentwicklung, da er seit einigen Jahren nicht nur als Lernender sondern auch als Lehrer nach Neumarkt kommt, wo w\u00e4hrend der Sommermonate in unterschiedlichen Disziplinen Kurse abgehalten werden. Als Lehrer hat sich Hans Binder mittlerweile ein Stammpublikum schaffen k\u00f6nnen und als Lernender begann er sich unter der Anleitung von Christoph Donin* mit Radierung zu besch\u00e4ftigen.<\/p>\n<p>Mittlerweile ist die Radierung mit ihren geradezu unendlich vielen graphischen M\u00f6glichkeiten zur zweiten k\u00fcnstlerischen Ausdrucksform herangewachsen. Auch in diesem Medium spielt die Landschaft die Hauptrolle, aber neue Themen sind hinzugekommen. Stillleben mit Tieren und Pflanzen haben das Interesse des K\u00fcnstlers geweckt.<\/p>\n<p>Nun stellen sich mit der Druckgraphik aber neue k\u00fcnstlerische Aufgaben, da die Farbe, die im Aquarell fl\u00fcssig zu kleinen Teichen mit dunklen R\u00e4ndern gerinnt, in der Druckgraphik eine andere Sprache spricht. Das Erscheinungsbild der Fl\u00fcssigkeit des Aquarells ist technisch in der Radierung zwar umsetzbar \u2013 sei es durch Zuckertusche oder freie \u00c4tzung auf Aquatinta \u2013 aber die Wirkung ist doch eine andere, da die Farbe zumeist auf einen Ton, sei dieser schwarz, braun oder ein anderer, beschr\u00e4nkt bleibt. \u201eFarbigkeit\u201c entsteht aus einer F\u00fclle graphischer Valeurs zumeist eines Farbtones, der den Reiz der Druckgraphik ausmacht. Auch hier hat Hans Binder zu seiner eigenen Tonigkeit gefunden, die zwischen Braungr\u00fcn und Gr\u00fcnbraun changiert. Nur selten finden sich Abz\u00fcge in schwarz. Meist handelt es sich um erste Probedrucke, die anzeigen sollen, wie weit die \u00c4tzung einer Linie erfolgreich war oder die Tiefe der Aquatintafl\u00e4chen f\u00fcr einen Plattenton ausreichen. Bietet das Aquarell noch die M\u00f6glichkeit der Ver\u00e4nderung von Farbe und Struktur \u2013 wenn man z.B. die getrocknete Oberfl\u00e4che \u00fcbermalt \u2013 so ist dies in der Radierung erheblich schwieriger und erfordert viel Geschick. Manches l\u00e4sst sich kaum tilgen, anderes nur verst\u00e4rken. Ist eine Linie in die Kupferplatte tief einge\u00e4tzt, dann gibt es kaum eine M\u00f6glichkeit, diese Vertiefung ganz heraus zu schleifen. Oft bleibt nur die M\u00f6glichkeit, die problematische Stelle zu verst\u00e4rken und dadurch zu ver\u00e4ndern.<\/p>\n<p>Nicht zuf\u00e4llig kommt Hans Binder zur Radierung, da diese graphische Technik ebenso wie das Aquarell mit seinen hinzugef\u00fcgten Papierstrukturen Zonen des \u201eZuf\u00e4lligen\u201c bietet. S\u00e4ureflecken, unterschiedlich ge\u00e4tzte Aquatintazonen sind gestaltende Ma\u00dfnahmen, um R\u00e4umlichkeit, Licht- und Schattenzonen zu formen und graphische Akzente zu setzen. Doch die Technik erfordert mehr Pr\u00e4zision \u2013 was im flie\u00dfenden Duktus des Aquarells noch geduldet wird, findet in der Radierung keine Gnade mehr. Gerade das macht aber einen Teil der Herausforderung der druckgraphischen Technik aus.<\/p>\n<p>Hans Binder geht noch einen Schritt weiter, er verbindet in den j\u00fcngsten Arbeiten Radierung mit Aquarell, ein teilweise risikoreiches Vorgehen, da beide graphischen Techniken eigene Spielregeln haben und sich nicht immer vertragen. Doch im Stadium des Experimentes ist zun\u00e4chst alles erlaubt. Es dient ja der Gestaltwerdung und gibt den Ideen einen Freiraum. Prophezeiungen sind hier nicht angebracht, doch es stellt sich die Frage, ob Hans Binder f\u00fcr sich einen neuen Weg entwickeln wird, der das haptische Moment der im Aquarell angewendeten Papierstrukturen mit den ge\u00e4tzten Fl\u00e4chen und graphischen Akzenten der Radierung verbinden wird. Die n\u00e4chsten Jahre werden dies weisen.<\/p>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:15px;width:100%;\"><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-1{width:60% !important;margin-top : 20px;margin-bottom : 20px;}.fusion-builder-column-1 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 3.2%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 3.2%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_2_5 2_5 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:center center;background-blend-mode: overlay;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;border-width: 30px 30px 30px 30px;border-color:var(--awb-color1);border-style:solid;box-shadow:0px 20px 50px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),calc( var(--awb-color8-l) - 9% ),calc( var(--awb-color8-a) - 94% ));;padding: 20px 20px 0px 20px;\"><div class=\"fusion-text fusion-text-2\"><p>Veronika Birke<\/p>\n<p>April 2008<\/p>\n<p>HR Dr. Veronika Birke, geboren 1943 in Wien. Studium der Psychologie, Kunstgeschichte und Arch\u00e4ologie in Wien. 1974 Promotion zum Dr. phil.<\/p>\n<p>1994 \u2013 1999 Vizedirektorin der Albertina <a href=\"https:\/\/www.drbirke.at\">https:\/\/www.drbirke.at<\/a><\/p>\n<p><em>*Christopf Donin (1930 Bregenz \u2013 2013 Wien) studierte an der Akademie f\u00fcr angewandte Kunst in Wien bei Ceno Kosak und Druckgraphik bei Franz Herbert.<\/em><\/p>\n<p><em>\u00a0Er war K\u00fcnstler und einer der versiertesten Druckgraphiker \u00d6sterreichs<\/em><\/p>\n<\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-2{width:40% !important;margin-top : 20px;margin-bottom : 20px;}.fusion-builder-column-2 > .fusion-column-wrapper {padding-top : 20px !important;padding-right : 20px !important;margin-right : 12%;padding-bottom : 0px !important;padding-left : 20px !important;margin-left : 4.8%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-2{width:100% !important;order : 0;}.fusion-builder-column-2 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-2{width:100% !important;order : 0;}.fusion-builder-column-2 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 2%;margin-top : 0px;padding-right : 0px;padding-bottom : 2%;margin-bottom : 0px;padding-left : 0px;}@media only screen and (max-width:1024px) {.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 80px;padding-bottom : 40px;}}@media only screen and (max-width:640px) {.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 32px;}}<\/style><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"footnotes":""},"class_list":["post-2447","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vorwort von Kunsthistorikerin - Hans H. Binder<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hans-h-binder.com\/de\/vorwort-von-kunsthistorikerin\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vorwort von Kunsthistorikerin - Hans H. Binder\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hans-h-binder.com\/de\/vorwort-von-kunsthistorikerin\/\" \/>\n<meta property=\"og:site_name\" content=\"Hans H. Binder\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-18T12:51:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"12\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hans-h-binder.com\\\/de\\\/vorwort-von-kunsthistorikerin\\\/\",\"url\":\"https:\\\/\\\/hans-h-binder.com\\\/de\\\/vorwort-von-kunsthistorikerin\\\/\",\"name\":\"Vorwort von Kunsthistorikerin - Hans H. Binder\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hans-h-binder.com\\\/#website\"},\"datePublished\":\"2022-12-14T14:43:43+00:00\",\"dateModified\":\"2023-01-18T12:51:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hans-h-binder.com\\\/de\\\/vorwort-von-kunsthistorikerin\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hans-h-binder.com\\\/de\\\/vorwort-von-kunsthistorikerin\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hans-h-binder.com\\\/de\\\/vorwort-von-kunsthistorikerin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Po\u010detna stranica\",\"item\":\"https:\\\/\\\/hans-h-binder.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vorwort von Kunsthistorikerin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hans-h-binder.com\\\/#website\",\"url\":\"https:\\\/\\\/hans-h-binder.com\\\/\",\"name\":\"Hans H. Binder\",\"description\":\"Akvareli i bakropisi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hans-h-binder.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vorwort von Kunsthistorikerin - Hans H. Binder","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hans-h-binder.com\/de\/vorwort-von-kunsthistorikerin\/","og_locale":"de_DE","og_type":"article","og_title":"Vorwort von Kunsthistorikerin - Hans H. Binder","og_url":"https:\/\/hans-h-binder.com\/de\/vorwort-von-kunsthistorikerin\/","og_site_name":"Hans H. Binder","article_modified_time":"2023-01-18T12:51:09+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"12\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hans-h-binder.com\/de\/vorwort-von-kunsthistorikerin\/","url":"https:\/\/hans-h-binder.com\/de\/vorwort-von-kunsthistorikerin\/","name":"Vorwort von Kunsthistorikerin - Hans H. Binder","isPartOf":{"@id":"https:\/\/hans-h-binder.com\/#website"},"datePublished":"2022-12-14T14:43:43+00:00","dateModified":"2023-01-18T12:51:09+00:00","breadcrumb":{"@id":"https:\/\/hans-h-binder.com\/de\/vorwort-von-kunsthistorikerin\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hans-h-binder.com\/de\/vorwort-von-kunsthistorikerin\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hans-h-binder.com\/de\/vorwort-von-kunsthistorikerin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Po\u010detna stranica","item":"https:\/\/hans-h-binder.com\/de\/"},{"@type":"ListItem","position":2,"name":"Vorwort von Kunsthistorikerin"}]},{"@type":"WebSite","@id":"https:\/\/hans-h-binder.com\/#website","url":"https:\/\/hans-h-binder.com\/","name":"Hans H. Binder","description":"Akvareli i bakropisi","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hans-h-binder.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/hans-h-binder.com\/de\/wp-json\/wp\/v2\/pages\/2447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hans-h-binder.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hans-h-binder.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hans-h-binder.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hans-h-binder.com\/de\/wp-json\/wp\/v2\/comments?post=2447"}],"version-history":[{"count":11,"href":"https:\/\/hans-h-binder.com\/de\/wp-json\/wp\/v2\/pages\/2447\/revisions"}],"predecessor-version":[{"id":2833,"href":"https:\/\/hans-h-binder.com\/de\/wp-json\/wp\/v2\/pages\/2447\/revisions\/2833"}],"wp:attachment":[{"href":"https:\/\/hans-h-binder.com\/de\/wp-json\/wp\/v2\/media?parent=2447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}